{"id":5278,"date":"2024-12-12T01:19:30","date_gmt":"2024-12-12T09:19:30","guid":{"rendered":"https:\/\/arbiosbiotech.com\/story\/josephine-carlton\/"},"modified":"2025-01-24T15:42:08","modified_gmt":"2025-01-24T23:42:08","slug":"josephine-carlton","status":"publish","type":"story","link":"https:\/\/arbiosbiotech.com\/fr\/story\/josephine-carlton\/","title":{"rendered":"Josephine Carlton"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Quelles sont les comp\u00e9tences qui ont le plus contribu\u00e9 \u00e0 votre croissance et \u00e0 votre r\u00e9ussite chez Arbios ?<\/h4>\n\n<p class=\"wp-block-paragraph\">La planification et l&rsquo;organisation ont \u00e9t\u00e9 essentielles, surtout lorsqu&rsquo;il s&rsquo;agissait d&rsquo;orchestrer les \u00e9v\u00e9nements de l&rsquo;entreprise et de la communaut\u00e9 pour cr\u00e9er des exp\u00e9riences m\u00e9morables (ma passion pas si secr\u00e8te !). La capacit\u00e9 d&rsquo;adaptation a \u00e9galement \u00e9t\u00e9 essentielle, qu&rsquo;il s&rsquo;agisse de se rendre \u00e0 Prince George \u00e0 court pr\u00e9avis ou de s&rsquo;attaquer \u00e0 des projets que d&rsquo;autres jugent impossibles. Remarque : j&rsquo;adore secr\u00e8tement que quelqu&rsquo;un me dise que quelque chose est impossible ! Je crois que tout peut \u00eatre r\u00e9solu et je suis toujours pr\u00eate \u00e0 relever le d\u00e9fi. Comme je suis bas\u00e9e \u00e0 Vancouver, Prince George n&rsquo;est peut-\u00eatre pas chez moi, mais je suis pr\u00eate \u00e0 vivre une aventure difficile. Si vous aimez le plein air, Prince George a beaucoup \u00e0 offrir. Tant que je conduis une camionnette et que je peux porter mon \u00e9quipement de plein air, je suis partant !      <\/p>\n\n<h4 class=\"wp-block-heading\">Qu&rsquo;est-ce qui vous stimule le plus dans votre travail avec Arbios ?<\/h4>\n\n<p class=\"wp-block-paragraph\">En plus de mon chien qui me tient en haleine, ce sont certainement mes co\u00e9quipiers qui apportent le plus d&rsquo;\u00e9nergie \u00e0 mon travail. J&rsquo;adore entendre les histoires de coll\u00e8gues dont les animaux de compagnie sont aussi leurs \u00ab\u00a0superviseurs\u00a0\u00bb &#8211; c&rsquo;est agr\u00e9able de savoir que je ne suis pas la seule ! En tant que \u00ab\u00a0plus ancien employ\u00e9\u00a0\u00bb d&rsquo;Arbios (je suis l\u00e0 depuis le premier jour), j&rsquo;ai eu la chance de voir notre \u00e9quipe grandir et notre culture prendre vie. Il y a des gens vraiment merveilleux ici, et leur engagement envers notre mission est contagieux. La passion et l&rsquo;enthousiasme de nos fondateurs ne font qu&rsquo;ajouter \u00e0 cette \u00e9nergie. L&rsquo;organisation d&rsquo;\u00e9v\u00e9nements &#8211; qu&rsquo;il s&rsquo;agisse d&rsquo;une grande c\u00e9l\u00e9bration ou d&rsquo;une simple discussion autour d&rsquo;un caf\u00e9 &#8211; me rend heureuse et me motive. Cr\u00e9er des liens et favoriser des relations authentiques a \u00e9t\u00e9 l&rsquo;une des plus grandes joies de mon parcours au sein d&rsquo;Arbios.      <\/p>\n\n<h4 class=\"wp-block-heading\">Qu&rsquo;est-ce qui vous enthousiasme le plus dans l&rsquo;avenir de la biotechnologie durable ?<\/h4>\n\n<p class=\"wp-block-paragraph\">L&rsquo;avenir de la biotechnologie durable ressemble \u00e0 un m\u00e9lange magique de science, d&rsquo;innovation et de conservation de la nature &#8211; c&rsquo;est vraiment captivant. Je suis particuli\u00e8rement enthousiaste quant au potentiel des \u00e9nergies renouvelables et des technologies respectueuses de l&rsquo;environnement qui feront une r\u00e9elle diff\u00e9rence. Notre relation avec les Premi\u00e8res nations Lheidli T&rsquo;enneh a renforc\u00e9 mon appr\u00e9ciation de l&rsquo;environnement et de l&rsquo;importance du respect et de la protection de la terre. Leur d\u00e9vouement \u00e0 la pr\u00e9servation de la nature est une source d&rsquo;inspiration, et il est clair qu&rsquo;ils soutiennent Arbios avec autant d&rsquo;ardeur.   <\/p>\n\n<p class=\"wp-block-paragraph\">Partager nos progr\u00e8s avec les parties prenantes et les inspirer pour la suite est l&rsquo;une des parties de mon travail que je pr\u00e9f\u00e8re. Je crois sinc\u00e8rement que nous sommes \u00e0 la veille de perc\u00e9es qui pourraient tout changer. Je soup\u00e7onne nos propri\u00e9taires d&rsquo;\u00eatre prudemment optimistes quant \u00e0 notre impact, mais ils nous consid\u00e9reront bient\u00f4t comme un \u00e9l\u00e9ment essentiel de leur avenir &#8211; une vitrine pour les solutions durables.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Josephine r\u00e9fl\u00e9chit \u00e0 son r\u00f4le en tant que plus ancienne employ\u00e9e d&rsquo;Arbios, soulignant sa passion pour l&rsquo;organisation d&rsquo;\u00e9v\u00e9nements, le d\u00e9veloppement de la communaut\u00e9 et les aventures en plein air \u00e0 Prince George. Elle partage son enthousiasme pour l&rsquo;innovation durable et les partenariats avec les Premi\u00e8res nations. <\/p>\n","protected":false},"featured_media":4137,"menu_order":0,"template":"","meta":{"_acf_changed":false,"jormi_team_member_description":"","jormi_team_member_position":"","jormi_team_member_image_url":"https:\/\/arbiosbiotech.com\/wp-content\/themes\/jormi\/assets\/images\/sample_800x800.jpg","jormi_team_member_image_alt":"Photo Alt","jormi_event_description":"","header_tags":"","footer_tags":"","custom_email":"","custom_phone":"","faq_items":""},"class_list":["post-5278","story","type-story","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/arbiosbiotech.com\/fr\/wp-json\/wp\/v2\/story\/5278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arbiosbiotech.com\/fr\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/arbiosbiotech.com\/fr\/wp-json\/wp\/v2\/types\/story"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arbiosbiotech.com\/fr\/wp-json\/wp\/v2\/media\/4137"}],"wp:attachment":[{"href":"https:\/\/arbiosbiotech.com\/fr\/wp-json\/wp\/v2\/media?parent=5278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}